{"id":12537,"date":"2023-04-04T15:02:50","date_gmt":"2023-04-04T15:02:50","guid":{"rendered":"https:\/\/sogimut.com\/prodotto\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/"},"modified":"2023-04-04T15:02:50","modified_gmt":"2023-04-04T15:02:50","slug":"serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw","status":"publish","type":"product","link":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/","title":{"rendered":"Serie 4 pezzi per autocentranti ghisa &#8211; acciaio &#8211; Griffe dritte"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7820,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[315,533],"product_tag":[585],"azienda":[562],"class_list":["post-12537","product","type-product","status-publish","has-post-thumbnail","product_cat-lathe-chucks","product_cat-ricambi-en","product_tag-guida-semplice-en","azienda-wessel-en","first","instock","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serie 4 pezzi per autocentranti ghisa - acciaio - Griffe dritte - Sogimut<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serie 4 pezzi per autocentranti ghisa - acciaio - Griffe dritte - Sogimut\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/\" \/>\n<meta property=\"og:site_name\" content=\"Sogimut\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sogimut.com\/wp-content\/uploads\/2023\/04\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/\",\"url\":\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/\",\"name\":\"Serie 4 pezzi per autocentranti ghisa - acciaio - Griffe dritte - Sogimut\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sogimut.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg\",\"datePublished\":\"2023-04-04T15:02:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sogimut.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg\",\"contentUrl\":\"https:\\\/\\\/sogimut.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/product\\\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sogimut.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/sogimut.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Clamping technology\",\"item\":\"https:\\\/\\\/sogimut.com\\\/en\\\/categoria-prodotto\\\/clamping-technology\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lathe chucks\",\"item\":\"https:\\\/\\\/sogimut.com\\\/en\\\/categoria-prodotto\\\/clamping-technology\\\/lathe-chucks\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Serie 4 pezzi per autocentranti ghisa &#8211; acciaio &#8211; Griffe dritte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sogimut.com\\\/en\\\/\",\"name\":\"Sogimut\",\"description\":\"Accessori per macchine utensili\",\"publisher\":{\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sogimut.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/#organization\",\"name\":\"Sogimut\",\"url\":\"https:\\\/\\\/sogimut.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sogimut.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-payoff-blu.png\",\"contentUrl\":\"https:\\\/\\\/sogimut.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-payoff-blu.png\",\"width\":2563,\"height\":624,\"caption\":\"Sogimut\"},\"image\":{\"@id\":\"https:\\\/\\\/sogimut.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sogimut-srl\\\/?originalSubdomain=it\",\"https:\\\/\\\/www.youtube.com\\\/@PastorinoCarrelli\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serie 4 pezzi per autocentranti ghisa - acciaio - Griffe dritte - Sogimut","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/","og_locale":"en_US","og_type":"article","og_title":"Serie 4 pezzi per autocentranti ghisa - acciaio - Griffe dritte - Sogimut","og_url":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/","og_site_name":"Sogimut","og_image":[{"width":1200,"height":1200,"url":"https:\/\/sogimut.com\/wp-content\/uploads\/2023\/04\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/","url":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/","name":"Serie 4 pezzi per autocentranti ghisa - acciaio - Griffe dritte - Sogimut","isPartOf":{"@id":"https:\/\/sogimut.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/#primaryimage"},"image":{"@id":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/#primaryimage"},"thumbnailUrl":"https:\/\/sogimut.com\/wp-content\/uploads\/2023\/04\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg","datePublished":"2023-04-04T15:02:50+00:00","breadcrumb":{"@id":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/#primaryimage","url":"https:\/\/sogimut.com\/wp-content\/uploads\/2023\/04\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg","contentUrl":"https:\/\/sogimut.com\/wp-content\/uploads\/2023\/04\/HOL308P_WESSEL_RICAMBIO_GUIDA_SEMPLICE_4_PEZZI_01.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/sogimut.com\/en\/product\/serie-4-pezzi-per-autocentranti-ghisa-acciaio-griffe-dritte-hol308pw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sogimut.com\/en\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/sogimut.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Clamping technology","item":"https:\/\/sogimut.com\/en\/categoria-prodotto\/clamping-technology\/"},{"@type":"ListItem","position":4,"name":"Lathe chucks","item":"https:\/\/sogimut.com\/en\/categoria-prodotto\/clamping-technology\/lathe-chucks\/"},{"@type":"ListItem","position":5,"name":"Serie 4 pezzi per autocentranti ghisa &#8211; acciaio &#8211; Griffe dritte"}]},{"@type":"WebSite","@id":"https:\/\/sogimut.com\/en\/#website","url":"https:\/\/sogimut.com\/en\/","name":"Sogimut","description":"Accessori per macchine utensili","publisher":{"@id":"https:\/\/sogimut.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sogimut.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sogimut.com\/en\/#organization","name":"Sogimut","url":"https:\/\/sogimut.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sogimut.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sogimut.com\/wp-content\/uploads\/2023\/01\/logo-payoff-blu.png","contentUrl":"https:\/\/sogimut.com\/wp-content\/uploads\/2023\/01\/logo-payoff-blu.png","width":2563,"height":624,"caption":"Sogimut"},"image":{"@id":"https:\/\/sogimut.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/sogimut-srl\/?originalSubdomain=it","https:\/\/www.youtube.com\/@PastorinoCarrelli\/featured"]}]}},"_links":{"self":[{"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/product\/12537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/media\/7820"}],"wp:attachment":[{"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/media?parent=12537"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/product_brand?post=12537"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/product_cat?post=12537"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/product_tag?post=12537"},{"taxonomy":"azienda","embeddable":true,"href":"https:\/\/sogimut.com\/en\/wp-json\/wp\/v2\/azienda?post=12537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}